{"id":14863,"date":"2026-03-23T13:36:16","date_gmt":"2026-03-23T16:36:16","guid":{"rendered":"https:\/\/pitubaemfoco.com.br\/?p=14863"},"modified":"2026-03-23T13:36:16","modified_gmt":"2026-03-23T16:36:16","slug":"apos-goleada-sofrida-contra-o-remo-bahia-vai-ao-topo-de-ranking-negativo","status":"publish","type":"post","link":"https:\/\/pitubaemfoco.com.br\/index.php\/2026\/03\/23\/apos-goleada-sofrida-contra-o-remo-bahia-vai-ao-topo-de-ranking-negativo\/","title":{"rendered":"Ap\u00f3s goleada sofrida contra o Remo, Bahia vai ao topo de ranking negativo"},"content":{"rendered":"<p>As consequ\u00eancias sofridas pelo Bahia na derrota para o Remo, pela oitava rodada do Campeonato Brasileiro, ainda refletem negativamente. No domingo (22), no Est\u00e1dio Mangueir\u00e3o, em Bel\u00e9m, o Esquadr\u00e3o foi goleado por 4 x 1.<\/p>\n<p>A derrota n\u00e3o s\u00f3 tirou os 100% de aproveitamento do Tricolor fora de casa, como tamb\u00e9m a invencibilidade no Brasileir\u00e3o. Al\u00e9m disso, o Bahia se tornou o clube brasileiro que mais sofreu goleadas neste s\u00e9culo.<\/p>\n<p>Segundo levantamento da p\u00e1gina R10 Score, o Esquadr\u00e3o ultrapassou o Ava\u00ed e agora lidera o ranking negativo, com 90 goleadas sofridas no s\u00e9culo XXI.<\/p>\n<p>Agora, o Bahia ter\u00e1 nove dias para se preparar at\u00e9 o pr\u00f3ximo desafio, diante do Athletico Paranaense, na Arena Fonte Nova. A partida est\u00e1 marcada para 1\u00ba de abril, \u00e0s 20h, pela 9\u00aa rodada do Brasileir\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As consequ\u00eancias sofridas pelo Bahia na derrota para o Remo, pela oitava rodada do Campeonato Brasileiro, ainda refletem negativamente. No domingo (22), no Est\u00e1dio Mangueir\u00e3o, em Bel\u00e9m, o Esquadr\u00e3o foi goleado por 4 x 1. A derrota n\u00e3o s\u00f3 tirou os 100% de aproveitamento do Tricolor fora de casa, como tamb\u00e9m a invencibilidade no Brasileir\u00e3o. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14865,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89],"tags":[],"class_list":["post-14863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14863"}],"version-history":[{"count":1,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14863\/revisions"}],"predecessor-version":[{"id":14864,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14863\/revisions\/14864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/media\/14865"}],"wp:attachment":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}