{"id":2232,"date":"2023-08-01T14:20:11","date_gmt":"2023-08-01T17:20:11","guid":{"rendered":"https:\/\/salvadoracontece.com.br\/?p=2232"},"modified":"2023-08-01T14:20:11","modified_gmt":"2023-08-01T17:20:11","slug":"isencao-de-imposto-para-compras-internacionais-de-ate-us-50-comeca-hoje-veja-o-que-muda","status":"publish","type":"post","link":"https:\/\/pitubaemfoco.com.br\/index.php\/2023\/08\/01\/isencao-de-imposto-para-compras-internacionais-de-ate-us-50-comeca-hoje-veja-o-que-muda\/","title":{"rendered":"Isen\u00e7\u00e3o de imposto para compras internacionais de at\u00e9 US$ 50 come\u00e7a hoje; veja o que muda"},"content":{"rendered":"\n<p>Come\u00e7a a valer nesta ter\u00e7a-feira, 1, a portaria&nbsp;que estabelece uma al\u00edquota zero do imposto de importa\u00e7\u00e3o sobre&nbsp;compras &nbsp;internacionais feitas pela internet&nbsp;de at\u00e9 US$ 50.&nbsp;A medida s\u00f3 vale para empresas que atenderem o plano de conformidade do governo, ou seja, que estiverem em dia com suas obriga\u00e7\u00f5es tribut\u00e1rias.<\/p>\n\n\n\n<p>A regra de isen\u00e7\u00e3o nas compras de at\u00e9 US$ 50 valia exclusivamente para remessas entre pessoas f\u00edsicas. Agora, passa a valer de empresa para consumidores. As compras online de at\u00e9 US$ 50, realizadas em empresas que n\u00e3o cumprirem com suas obriga\u00e7\u00f5es,&nbsp;continuar\u00e3o sendo taxadas.<\/p>\n\n\n\n<p>&#8220;Fica reduzida para 0% a al\u00edquota do Imposto de Importa\u00e7\u00e3o incidente sobre os bens integrantes de remessa postal ou de encomenda a\u00e9rea internacional no valor de at\u00e9 US$ 50, ou o equivalente em outra moeda, destinados a pessoa f\u00edsica, desde que as empresas atendam aos requisitos do programa de conformidade, inclusive o recolhimento do tributo estadual incidente sobre a importa\u00e7\u00e3o&#8221;, cita a portaria da Fazenda.<\/p>\n\n\n\n<p>A portaria foi anunciada mais de um m\u00eas ap\u00f3s o Minist\u00e9rio da Fazenda e a Receita Federal afirmarem que iriam extinguir a isen\u00e7\u00e3o para o com\u00e9rcio internacional entre pessoas f\u00edsicas no valor de at\u00e9&nbsp;US$ 50. O governo defendeu que a regra era usada de forma irregular por varejistas internacionais, como a Shein e a Shopee, que usavam a op\u00e7\u00e3o de pessoa f\u00edsica para n\u00e3o pagar impostos.&nbsp;<\/p>\n\n\n\n<p>Uma semana ap\u00f3s o an\u00fancio, o governo voltou atr\u00e1s e afirmou que n\u00e3o iria acabar com a isen\u00e7\u00e3o. Haddad, na \u00e9poca, disse que o governo iria criar regras para endurecer o com\u00e9rcio internacional irregular.<\/p>\n\n\n\n<p>Em meio \u00e0 pol\u00eamica, a Shein se reuniu com o governo e assumiu o compromisso de&nbsp;investir R$ 750 milh\u00f5es no Brasil. A varejista passar\u00e1 a produzir 85% de seu portf\u00f3lio com fabricantes locais e gerar at\u00e9 100 mil empregos no pa\u00eds em tr\u00eas anos.&nbsp;A previs\u00e3o \u00e9 de que uma f\u00e1brica do Rio Grande do Norte vai come\u00e7aria a produzir roupas para vendas na empresa em julho.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come\u00e7a a valer nesta ter\u00e7a-feira, 1, a portaria&nbsp;que estabelece uma al\u00edquota zero do imposto de importa\u00e7\u00e3o sobre&nbsp;compras &nbsp;internacionais feitas pela internet&nbsp;de at\u00e9 US$ 50.&nbsp;A medida s\u00f3 vale para empresas que atenderem o plano de conformidade do governo, ou seja, que estiverem em dia com suas obriga\u00e7\u00f5es tribut\u00e1rias. A regra de isen\u00e7\u00e3o nas compras de at\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,85],"tags":[],"class_list":["post-2232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-noticias"],"_links":{"self":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2232"}],"version-history":[{"count":0,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/media\/2233"}],"wp:attachment":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}