{"id":2263,"date":"2023-08-01T16:28:24","date_gmt":"2023-08-01T19:28:24","guid":{"rendered":"https:\/\/salvadoracontece.com.br\/?p=2263"},"modified":"2023-08-01T16:28:24","modified_gmt":"2023-08-01T19:28:24","slug":"idoso-e-assassinado-na-sua-residencia-em-camacari","status":"publish","type":"post","link":"https:\/\/pitubaemfoco.com.br\/index.php\/2023\/08\/01\/idoso-e-assassinado-na-sua-residencia-em-camacari\/","title":{"rendered":"Idoso \u00e9 assassinado na sua resid\u00eancia em Cama\u00e7ari"},"content":{"rendered":"\n<p>Um idoso de 63 anos, identificado pela Pol\u00edcia como Sr. Josu\u00e9 Gomes da Silva, foi assassinado na noite de ontem (31) ap\u00f3s ter a sua casa invadida na Rua do Areal, em&nbsp;Monte Gordo, distrito de&nbsp;Cama\u00e7ari.<\/p>\n\n\n\n<p>Policiais militares da 33\u00aa Delegacia Territorial (DT) foram acionados, por\u00e9m, ao chegarem no local da ocorr\u00eancia o idoso j\u00e1 estava morto. O local foi isolado para realiza\u00e7\u00e3o da per\u00edcia. A autoria e motiva\u00e7\u00e3o do crime est\u00e3o sendo investigadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um idoso de 63 anos, identificado pela Pol\u00edcia como Sr. Josu\u00e9 Gomes da Silva, foi assassinado na noite de ontem (31) ap\u00f3s ter a sua casa invadida na Rua do Areal, em&nbsp;Monte Gordo, distrito de&nbsp;Cama\u00e7ari. Policiais militares da 33\u00aa Delegacia Territorial (DT) foram acionados, por\u00e9m, ao chegarem no local da ocorr\u00eancia o idoso j\u00e1 estava [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,83],"tags":[],"class_list":["post-2263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-seguranca"],"_links":{"self":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2263"}],"version-history":[{"count":0,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/media\/2264"}],"wp:attachment":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}