{"id":7790,"date":"2024-01-30T10:23:52","date_gmt":"2024-01-30T13:23:52","guid":{"rendered":"https:\/\/pitubaemfoco.com.br\/?p=7790"},"modified":"2024-01-30T10:23:54","modified_gmt":"2024-01-30T13:23:54","slug":"tj-ba-define-nesta-segunda-se-iuri-sheik-vai-a-juri-popular","status":"publish","type":"post","link":"https:\/\/pitubaemfoco.com.br\/index.php\/2024\/01\/30\/tj-ba-define-nesta-segunda-se-iuri-sheik-vai-a-juri-popular\/","title":{"rendered":"TJ-BA define nesta segunda se Iuri Sheik vai a j\u00fari popular"},"content":{"rendered":"\n<p>O digital influencer Iuri Santos Abra\u00e3o, mais conhecido com Iuri Sheik, ser\u00e1 julgado nesta segunda-feira (29),&nbsp;suspeito de matar, o empres\u00e1rio William Oliveira ap\u00f3s uma discuss\u00e3o durante uma festa de S\u00e3o Jo\u00e3o, em Santo Ant\u00f4nio de Jesus, no dia 23 de junho de 2019.&nbsp;<\/p>\n\n\n\n<p>O juiz da 1\u00aa Vara Criminal da Comarca de Santo Ant\u00f4nio de Jesus, decidiu em outuro de 2022, que o r\u00e9u vai a j\u00fari popular, por\u00e9m, a defesa de Iuri Sheik recorreu da decis\u00e3o.&nbsp;<\/p>\n\n\n\n<p>O advogado representante da fam\u00edlia de William, Wyre Souza, relatou a situa\u00e7\u00e3o. &#8220;Tivemos uma vit\u00f3ria em primeira inst\u00e2ncia, quando o juiz de Santo Ant\u00f4nio de Jesus pronunciou o r\u00e9u a ir a j\u00fari popular, no entanto, a lei abre margem para recursos. Foi o que os advogados dele fizeram: recorreram da decis\u00e3o, levando o caso para a segunda inst\u00e2ncia. Estamos crentes, com base no processo e em todas as testemunhas que foram ouvidas, que a justi\u00e7a tarda, mas n\u00e3o falha, e que ele ir\u00e1 a j\u00fari popular logo mais\u201d.<\/p>\n\n\n\n<p>Diante disso, o Tribunal de Justi\u00e7a da Bahia decidir\u00e1 nesta segunda-feira (29),&nbsp;&nbsp;se mant\u00e9m a decis\u00e3o da 1\u00aa Vara Criminal da Comarca de Santo Ant\u00f4nio de Jesus e Iuri vai \u00e0 j\u00fari popular ou n\u00e3o. &nbsp;<\/p>\n\n\n\n<p>Fonte: Varela Net <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O digital influencer Iuri Santos Abra\u00e3o, mais conhecido com Iuri Sheik, ser\u00e1 julgado nesta segunda-feira (29),&nbsp;suspeito de matar, o empres\u00e1rio William Oliveira ap\u00f3s uma discuss\u00e3o durante uma festa de S\u00e3o Jo\u00e3o, em Santo Ant\u00f4nio de Jesus, no dia 23 de junho de 2019.&nbsp; O juiz da 1\u00aa Vara Criminal da Comarca de Santo Ant\u00f4nio de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106],"tags":[],"class_list":["post-7790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justica"],"_links":{"self":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7790"}],"version-history":[{"count":1,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7790\/revisions"}],"predecessor-version":[{"id":7792,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7790\/revisions\/7792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/media\/7791"}],"wp:attachment":[{"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pitubaemfoco.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}